{"id":3099,"date":"2014-11-21T04:34:47","date_gmt":"2014-11-21T04:34:47","guid":{"rendered":"http:\/\/oshine.wpengine.com\/?page_id=3099"},"modified":"2014-11-21T04:34:47","modified_gmt":"2014-11-21T04:34:47","slug":"services-3","status":"publish","type":"page","link":"https:\/\/oshinewptheme.com\/v1\/services-3\/","title":{"rendered":"Services"},"content":{"rendered":"<div  class=\"tatsu-igpjlfozxg99433v tatsu-section    tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='50px 0% 50px 0%' data-padding-top='50px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-igpjlfp0hp7mfmro\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-no-bg tatsu-one-col tatsu-column-image- tatsu-column-effect-  tatsu-igpjlfp0locntyn6\" data-animation=\"fadeIn\"   data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"special-heading-wrap style1 oshine-module  tatsu-igpjlfp0s9f270pb  \" data-animation=\"fadeIn\"  ><div class=\"special-heading align-left\"><h4 class=\"special-h-tag\" >SERVICES<\/h4><\/div><style>.tatsu-igpjlfp0s9f270pb .special-h-tag{color: #ffffff ;}<\/style><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-igpjlfp0locntyn6.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 0px 0px 0px 0px;}.tatsu-igpjlfp0locntyn6.tatsu-column > .tatsu-column-inner{border-width: 0 0 0 0;}.tatsu-igpjlfp0locntyn6.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-igpjlfp0locntyn6 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-igpjlfp0locntyn6 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp0locntyn6 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-igpjlfp0locntyn6 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}.tatsu-igpjlfp0locntyn6.tatsu-column{transform: translate3d(0px,0px, 0);}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background\" ><\/div><\/div><style>.tatsu-igpjlfozxg99433v.tatsu-section{background-color: #e0a240;margin: 0px 0px 0px 0px;}.tatsu-igpjlfozxg99433v{border-width: 0px 0px px 0px;border-color: #efefef; border-style: solid;}.tatsu-igpjlfozxg99433v .tatsu-section-pad{padding: 50px 0% 50px 0%;}.tatsu-igpjlfozxg99433v > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfozxg99433v > .tatsu-top-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-igpjlfozxg99433v{border-style: solid;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-igpjlfozxg99433v{border-style: solid;}}@media only screen and (max-width: 767px) {.tatsu-igpjlfozxg99433v{border-style: solid;}}<\/style><\/div><div  class=\"tatsu-igpjlfp0vw224aej tatsu-section    tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='90px 0% 90px 0%' data-padding-top='90px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-igpjlfp12i8sbxne\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-no-bg tatsu-one-col tatsu-column-image- tatsu-column-effect-  tatsu-igpjlfp16529fyw4\" data-animation=\"fadeIn\"   data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div class=\"services-outer-wrap oshine-module tatsu-igpjlfp1c090t2gw\"><ul class=\"be-services\"><li class=\"be-service tatsu-igpjlfp1faeycqcz\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-alarmclock icon-size-large\" ><\/i><div class=\"service-content\" ><h6>12 UNIQUE DEMOS<\/h6>\n<p>Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/p>\n<\/div><style>.tatsu-igpjlfp1faeycqcz .service-icon{background-color: #ececec;color: #000000 ;}.tatsu-igpjlfp1faeycqcz .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}.tatsu-igpjlfp1faeycqcz .service-content{background: #ffffff;}<\/style><\/div><\/li><li class=\"be-service tatsu-igpjlfp1jzmvzq4\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-strategy icon-size-large\" ><\/i><div class=\"service-content\" ><h6>50+ SHORTCODES<\/h6>\n<p>Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/p>\n<\/div><style>.tatsu-igpjlfp1jzmvzq4 .service-icon{background-color: #000000;color: #ffffff ;}.tatsu-igpjlfp1jzmvzq4 .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}<\/style><\/div><\/li><li class=\"be-service tatsu-igpjlfp1na20rcmm\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-basket icon-size-large\" ><\/i><div class=\"service-content\" ><h6>WOOCOMMERCE COMPATIBLE<\/h6>\n<p>Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/p>\n<\/div><style>.tatsu-igpjlfp1na20rcmm .service-icon{background-color: #ececec;color: #000000 ;}.tatsu-igpjlfp1na20rcmm .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}<\/style><\/div><\/li><li class=\"be-service tatsu-igpjlfp1pt272sin\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-icon_loading icon-size-large\" ><\/i><div class=\"service-content\" ><h6>ALL AJAX LOADING<\/h6>\n<p>Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/p>\n<\/div><style>.tatsu-igpjlfp1pt272sin .service-icon{background-color: #000000;color: #ffffff ;}.tatsu-igpjlfp1pt272sin .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}<\/style><\/div><\/li><\/ul><span class=\"timeline\" ><\/span><style>.tatsu-igpjlfp1c090t2gw .timeline{background: #dddddd;}<\/style><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-igpjlfp16529fyw4.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 0px 0px 0px 0px;}.tatsu-igpjlfp16529fyw4.tatsu-column > .tatsu-column-inner{border-width: 0 0 0 0;}.tatsu-igpjlfp16529fyw4.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-igpjlfp16529fyw4 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-igpjlfp16529fyw4 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp16529fyw4 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-igpjlfp16529fyw4 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}.tatsu-igpjlfp16529fyw4.tatsu-column{transform: translate3d(0px,0px, 0);}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background\" ><\/div><\/div><style>.tatsu-igpjlfp0vw224aej{border-width: 0px 0px 1px 0px;border-color: #dddddd; border-style: solid;}.tatsu-igpjlfp0vw224aej .tatsu-section-pad{padding: 90px 0% 90px 0%;}.tatsu-igpjlfp0vw224aej.tatsu-section{margin: 0px 0px 0px 0px;}.tatsu-igpjlfp0vw224aej > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp0vw224aej > .tatsu-top-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-igpjlfp0vw224aej{border-style: solid;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-igpjlfp0vw224aej{border-style: solid;}}@media only screen and (max-width: 767px) {.tatsu-igpjlfp0vw224aej{border-style: solid;}}<\/style><\/div><div  class=\"tatsu-igpjlfp1tc4vgz0x tatsu-section    tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='90px 0% 90px 0%' data-padding-top='90px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-igpjlfp20d1yyk7u\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-no-bg tatsu-one-col tatsu-column-image- tatsu-column-effect-  tatsu-igpjlfp2372o0fh2\" data-animation=\"fadeIn\"   data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"special-heading-wrap style1 oshine-module  tatsu-igpjlfp27i27xtgs  \" data-animation=\"fadeIn\"  ><div class=\"special-heading align-center\"><h5 class=\"special-h-tag\" >COMPLETELY CUSTOMIZABLE<\/h5><\/div><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-igpjlfp2372o0fh2.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 0px 0px 0px 0px;}.tatsu-igpjlfp2372o0fh2.tatsu-column > .tatsu-column-inner{border-width: 0 0 0 0;}.tatsu-igpjlfp2372o0fh2.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-igpjlfp2372o0fh2 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-igpjlfp2372o0fh2 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp2372o0fh2 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-igpjlfp2372o0fh2 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}.tatsu-igpjlfp2372o0fh2.tatsu-column{transform: translate3d(0px,0px, 0);}<\/style><\/div><\/div><\/div><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-igpjlfp29hcp85ma\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-no-bg tatsu-one-col tatsu-column-image- tatsu-column-effect-  tatsu-igpjlfp2bmki4h8\" data-animation=\"fadeIn\"   data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div class=\"services-outer-wrap oshine-module tatsu-igpjlfp2gh8r5w34\"><ul class=\"be-services\"><li class=\"be-service tatsu-igpjlfp2i9bfqbqe\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-house icon-size-small\" ><\/i><div class=\"service-content\" ><h6>ONE CLICK IMPORT<\/h6>\n<p>Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/p>\n<\/div><style>.tatsu-igpjlfp2i9bfqbqe .service-icon{background-color: #ececec;color: #000000 ;}.tatsu-igpjlfp2i9bfqbqe .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}.tatsu-igpjlfp2i9bfqbqe .service-content{background: #f2f0ed;}<\/style><\/div><\/li><li class=\"be-service tatsu-igpjlfp2la1g6ic0\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-icon_cloud-upload icon-size-medium\" ><\/i><div class=\"service-content\" ><h6><span style=\"color: #ffffff\">CUSTOM PAGE BUILDER<\/span><\/h6>\n<p><span style=\"color: #ffffff\">Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/span><\/p>\n<\/div><style>.tatsu-igpjlfp2la1g6ic0 .service-icon{background-color: #000000;color: #ffffff ;}.tatsu-igpjlfp2la1g6ic0 .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}.tatsu-igpjlfp2la1g6ic0 .service-content{background: #000000;}<\/style><\/div><\/li><li class=\"be-service tatsu-igpjlfp2o1dbkc03\"><div class=\"service-wrap\" ><i class=\"service-icon font-icon icon-language icon-size-large\" ><\/i><div class=\"service-content\" ><h6><span style=\"color: #ffffff\">WPML COMPATIBLE<\/span><\/h6>\n<p><span style=\"color: #ffffff\">Proin facilisis varius nunc. Curabitur eros risus, ultrices et dui ut, luctus accumsan nibh. Fusce convallis sapien placerat tellus suscipit vehicula.<\/span><\/p>\n<\/div><style>.tatsu-igpjlfp2o1dbkc03 .service-icon{background-color: #ececec;color: #000000 ;}.tatsu-igpjlfp2o1dbkc03 .service-wrap:hover .service-icon{background-color: #e0a240;color: #ffffff ;}.tatsu-igpjlfp2o1dbkc03 .service-content{background: #e0a240;}<\/style><\/div><\/li><\/ul><span class=\"timeline\" ><\/span><style>.tatsu-igpjlfp2gh8r5w34 .timeline{background: #dddddd;}<\/style><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-igpjlfp2bmki4h8.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 0px 0px 0px 0px;}.tatsu-igpjlfp2bmki4h8.tatsu-column > .tatsu-column-inner{border-width: 0 0 0 0;}.tatsu-igpjlfp2bmki4h8.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-igpjlfp2bmki4h8 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-igpjlfp2bmki4h8 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp2bmki4h8 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-igpjlfp2bmki4h8 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}.tatsu-igpjlfp2bmki4h8.tatsu-column{transform: translate3d(0px,0px, 0);}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background\" ><\/div><\/div><style>.tatsu-igpjlfp1tc4vgz0x{border-width: 0px 0px 1px 0px;border-color: #dddddd; border-style: solid;}.tatsu-igpjlfp1tc4vgz0x .tatsu-section-pad{padding: 90px 0% 90px 0%;}.tatsu-igpjlfp1tc4vgz0x.tatsu-section{margin: 0px 0px 0px 0px;}.tatsu-igpjlfp1tc4vgz0x > .tatsu-bottom-divider{z-index: 9999;}.tatsu-igpjlfp1tc4vgz0x > .tatsu-top-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-igpjlfp1tc4vgz0x{border-style: solid;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-igpjlfp1tc4vgz0x{border-style: solid;}}@media only screen and (max-width: 767px) {.tatsu-igpjlfp1tc4vgz0x{border-style: solid;}}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/oshinewptheme.com\/v1\/services-3\/\" class=\"more-link style1-button\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3099","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/pages\/3099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/comments?post=3099"}],"version-history":[{"count":0,"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/pages\/3099\/revisions"}],"wp:attachment":[{"href":"https:\/\/oshinewptheme.com\/v1\/wp-json\/wp\/v2\/media?parent=3099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}